{"id":1865,"date":"2022-08-03T05:15:29","date_gmt":"2022-08-03T05:15:29","guid":{"rendered":"https:\/\/endlesssurf.com\/2022\/08\/03\/5-surf-park-design-tips-for-developers\/"},"modified":"2022-11-10T07:28:44","modified_gmt":"2022-11-10T07:28:44","slug":"5-dicas-de-design-de-surf-park-para-desenvolvedores","status":"publish","type":"post","link":"https:\/\/endlesssurf.com\/br\/2022\/08\/03\/5-dicas-de-design-de-surf-park-para-desenvolvedores\/","title":{"rendered":"5 DICAS DE DESIGN DE SURF PARK PARA DESENVOLVEDORES"},"content":{"rendered":"<p>Estamos em uma posi\u00e7\u00e3o privilegiada para conhecer os Surf Parks em desenvolvimento antes de seu an\u00fancio p\u00fablico, e podemos dizer com confian\u00e7a que vemos locais de surf do interior se expandindo para diferentes mercados globalmente. Por qu\u00ea? A procura pela experi\u00eancia de surf est\u00e1, sem d\u00favida, cada vez mais forte entre os consumidores que impulsionam estes projetos. Esses \u201cnovos\u201d tipos de desenvolvimento de surf, sejam para urbaniza\u00e7\u00e3o, hotel e resort ou entretenimento (entre muitos outros), exigem abordagens \u00fanicas quando se trata de design de surf parks. Mas n\u00e3o importa qu\u00e3o diferentes sejam as comodidades extras ao redor da piscina, o objetivo geralmente permanece o mesmo: fornecer um ambiente de surf excepcionalmente aut\u00eantico para surfistas e convidados.<\/p>\n<p>Embora possa parecer simples, h\u00e1 muitas nuances no design de surf parks. E para oferecer algumas dicas sobre a arte do design de locais de surf, sentamos para conversar com nosso pr\u00f3prio Diretor de Cria\u00e7\u00e3o Arquitet\u00f4nica, Anthony Marinakis. Ele, geralmente, n\u00e3o gosta de holofotes, mas para resumir, o Anthony tem quase 30 anos de experi\u00eancia nesta \u00e1rea e trabalhou com algumas das marcas mais reconhecidas do mundo durante seu tempo na WhiteWater e Endless Surf. Ent\u00e3o aqui v\u00e3o 5 dicas do pr\u00f3prio especialista:<\/p>\n<h3><strong>1. Mantenha-se fiel \u00e0 vibra\u00e7\u00e3o do seu local<br \/>\n<\/strong><\/h3>\n<p>Esta dica inicial parece simples, mas pela minha experi\u00eancia, pode quebrar um local de surf. Dependendo de fatores como a localiza\u00e7\u00e3o, o p\u00fablico-alvo, o tipo de empreendimento e os arredores, a cria\u00e7\u00e3o da atmosfera certa para o seu local requer alguma reflex\u00e3o. No meu papel ajudando a projetar locais em torno de nossos produtos na WhiteWater, e agora em torno do Endless Surf, isso geralmente \u00e9 o primeiro passo, pois ajuda nossos clientes a descobrir o que pode tornar seu local especial. N\u00e3o \u00e9 nenhum segredo que os surfistas est\u00e3o atr\u00e1s de uma boa vibe, ent\u00e3o manter-se fiel \u00e0 sua singularidade \u00e9 importante. Eu vou dizer que ter boas ondas \u00e9 o mais importante para os surfistas, ent\u00e3o certifique-se de colocar o surf no centro dessas discuss\u00f5es. Mas, se voc\u00ea quiser que eles fiquem depois da sess\u00e3o, voc\u00ea tamb\u00e9m precisa criar a vibe.<\/p>\n<div class=\"w-gallery fit_cover wp_gallery type_grid action_popup_image ratio_1x1 count_3\" style=\"--columns:3;--items-gap:0px;\"><div class=\"w-gallery-list\"><div class=\"w-gallery-item\"><div class=\"w-gallery-item-img\"><img loading=\"lazy\" decoding=\"async\" width=\"400\" height=\"300\" src=\"https:\/\/endlesssurf.com\/wp-content\/uploads\/2022\/07\/220706-42990-La-Vague-Grand_View02.03-400x300.jpg\" class=\"attachment-us_400_300_crop size-us_400_300_crop\" alt=\"\" \/><\/div><div class=\"w-gallery-item-meta\"><div class=\"w-gallery-item-title\">The urban entertainment vibe<\/div><\/div><a class=\"w-gallery-item-link\" aria-label=\"The urban entertainment vibe\" href=\"https:\/\/endlesssurf.com\/wp-content\/uploads\/2022\/07\/220706-42990-La-Vague-Grand_View02.03-scaled.jpg\" title=\"The urban entertainment vibe\"><\/a><\/div><div class=\"w-gallery-item\"><div class=\"w-gallery-item-img\"><img loading=\"lazy\" decoding=\"async\" width=\"400\" height=\"300\" src=\"https:\/\/endlesssurf.com\/wp-content\/uploads\/2022\/07\/20210604-40030-ESMarketing-Cam3B-2-400x300.jpg\" class=\"attachment-us_400_300_crop size-us_400_300_crop\" alt=\"\" \/><\/div><div class=\"w-gallery-item-meta\"><div class=\"w-gallery-item-title\">The hardcore surf vibe<\/div><\/div><a class=\"w-gallery-item-link\" aria-label=\"The hardcore surf vibe\" href=\"https:\/\/endlesssurf.com\/wp-content\/uploads\/2022\/07\/20210604-40030-ESMarketing-Cam3B-2-scaled.jpg\" title=\"The hardcore surf vibe\"><\/a><\/div><div class=\"w-gallery-item\"><div class=\"w-gallery-item-img\"><img loading=\"lazy\" decoding=\"async\" width=\"400\" height=\"300\" src=\"https:\/\/endlesssurf.com\/wp-content\/uploads\/2022\/04\/Untitled-design-12-400x300.png\" class=\"attachment-us_400_300_crop size-us_400_300_crop\" alt=\"\" \/><\/div><div class=\"w-gallery-item-meta\"><div class=\"w-gallery-item-title\">The exclusive luxury vibe<\/div><\/div><a class=\"w-gallery-item-link\" aria-label=\"The exclusive luxury vibe\" href=\"https:\/\/endlesssurf.com\/wp-content\/uploads\/2022\/04\/Untitled-design-12.png\" title=\"The exclusive luxury vibe\"><\/a><\/div><\/div><\/div>\n<h3><strong>2. Concentre-se na coloca\u00e7\u00e3o da piscina de surf para aproveitar ao m\u00e1ximo o master plan<br \/>\n<\/strong><\/h3>\n<p>Muitas vezes esquecido, o posicionamento adequado da piscina de surf \u00e9 crucial para entender como os h\u00f3spedes circular\u00e3o pelo local. Os desenvolvedores devem primeiro considerar o tamanho do espa\u00e7o do local e quanto dele ser\u00e1 ocupado pela pr\u00f3pria piscina de surf. Em seguida, podemos sentar e mergulhar no local, nas comodidades adicionais e no fluxo de convidados pelo local. Al\u00e9m disso, (assim como eu mencionei que o surf deve sempre ser o centro de suas discuss\u00f5es de design) com a Endless Surf podemos literalmente colocar o lago no centro do local. Da minha perspectiva de design de local, adoro que a tecnologia n\u00e3o seja invasiva, n\u00e3o precise ser encurralada e tenha uma sensa\u00e7\u00e3o mais naturalista e aberta. Oferece 360 \u200b\u200bgraus de potencial de desenvolvimento ao redor da piscina, o que nos permite otimizar o fluxo e a circula\u00e7\u00e3o de h\u00f3spedes, mantendo vistas estelares.<\/p>\n<div class=\"w-gallery fit_cover wp_gallery type_grid ratio_1x1 count_2\" style=\"--columns:2;--items-gap:0px;\"><div class=\"w-gallery-list\"><div class=\"w-gallery-item\"><div class=\"w-gallery-item-img\"><img loading=\"lazy\" decoding=\"async\" width=\"1080\" height=\"1080\" src=\"https:\/\/endlesssurf.com\/wp-content\/uploads\/2022\/07\/B09DD938-231B-4457-945C-89FDDE55CF3D.jpg\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/endlesssurf.com\/wp-content\/uploads\/2022\/07\/B09DD938-231B-4457-945C-89FDDE55CF3D.jpg 1080w, https:\/\/endlesssurf.com\/wp-content\/uploads\/2022\/07\/B09DD938-231B-4457-945C-89FDDE55CF3D-300x300.jpg 300w, https:\/\/endlesssurf.com\/wp-content\/uploads\/2022\/07\/B09DD938-231B-4457-945C-89FDDE55CF3D-1024x1024.jpg 1024w, https:\/\/endlesssurf.com\/wp-content\/uploads\/2022\/07\/B09DD938-231B-4457-945C-89FDDE55CF3D-150x150.jpg 150w\" sizes=\"auto, (max-width: 1080px) 100vw, 1080px\" \/><\/div><div class=\"w-gallery-item-meta\"><div class=\"w-gallery-item-title\">Surf pool placement in master-planning is key<\/div><\/div><\/div><div class=\"w-gallery-item\"><div class=\"w-gallery-item-img\"><img loading=\"lazy\" decoding=\"async\" width=\"1080\" height=\"1080\" src=\"https:\/\/endlesssurf.com\/wp-content\/uploads\/2022\/07\/FBBF4968-9CA1-452E-B93E-DEB0D39CFEC5.jpg\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/endlesssurf.com\/wp-content\/uploads\/2022\/07\/FBBF4968-9CA1-452E-B93E-DEB0D39CFEC5.jpg 1080w, https:\/\/endlesssurf.com\/wp-content\/uploads\/2022\/07\/FBBF4968-9CA1-452E-B93E-DEB0D39CFEC5-300x300.jpg 300w, https:\/\/endlesssurf.com\/wp-content\/uploads\/2022\/07\/FBBF4968-9CA1-452E-B93E-DEB0D39CFEC5-1024x1024.jpg 1024w, https:\/\/endlesssurf.com\/wp-content\/uploads\/2022\/07\/FBBF4968-9CA1-452E-B93E-DEB0D39CFEC5-150x150.jpg 150w\" sizes=\"auto, (max-width: 1080px) 100vw, 1080px\" \/><\/div><div class=\"w-gallery-item-meta\"><div class=\"w-gallery-item-title\">Master-plans made with EDSA<\/div><\/div><\/div><\/div><\/div>\n<h3><strong>3. Aproveite ao m\u00e1ximo os espa\u00e7os \u00e0 beira-mar ao redor da piscina<br \/>\n<\/strong><\/h3>\n<p>A beira-mar \u00e9 um espa\u00e7o procurado e o principal motivo pelo qual as pessoas v\u00eam ao seu local \u2013 para surfar. Dependendo do desenvolvimento, pode aumentar imensamente os valores imobili\u00e1rios \u2013 pense no potencial de ROI com unidades residenciais \u00e0 beira-mar com vista para um surf break de classe. Ou, no m\u00ednimo, oferece um lugar para os h\u00f3spedes se divertirem e aumentar a dura\u00e7\u00e3o da estadia. Na minha fun\u00e7\u00e3o na Endless Surf, eu me divirto muito projetando ao redor da nossa orla. Isso se deve principalmente \u00e0 \u00e1rea maximizada \u00e0 beira-mar, ao potencial de constru\u00e7\u00e3o na parede de fundo da piscina e ao ponto em forma de \u201cU\u201d entre os dois picos, que oferece vistas \u00e9picas da esquerda e da direita. Seja t\u00e3o cl\u00e1ssico quanto as cabanas \u00e0 beira-mar ou t\u00e3o sofisticado quanto as banheiras de hidromassagem de borda infinita ao longo da parede traseira, adoro a criatividade que entra nessas discuss\u00f5es e planos.<\/p>\n<figure id=\"attachment_1091\" aria-describedby=\"caption-attachment-1091\" style=\"width: 2560px\" class=\"wp-caption alignnone\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-1091 size-full\" src=\"https:\/\/endlesssurf.com\/wp-content\/uploads\/2022\/07\/48_Parkwood_Wave_Pool_Aerial_ID-scaled.jpg\" alt=\"surf park design of The Club at Parkwood, Gold Coast\" width=\"2560\" height=\"1440\" srcset=\"https:\/\/endlesssurf.com\/wp-content\/uploads\/2022\/07\/48_Parkwood_Wave_Pool_Aerial_ID-scaled.jpg 2560w, https:\/\/endlesssurf.com\/wp-content\/uploads\/2022\/07\/48_Parkwood_Wave_Pool_Aerial_ID-300x169.jpg 300w, https:\/\/endlesssurf.com\/wp-content\/uploads\/2022\/07\/48_Parkwood_Wave_Pool_Aerial_ID-1024x576.jpg 1024w\" sizes=\"auto, (max-width: 2560px) 100vw, 2560px\" \/><figcaption id=\"caption-attachment-1091\" class=\"wp-caption-text\">The Club at Parkwood Village aproveitando ao m\u00e1ximo os im\u00f3veis \u00e0 beira-mar<\/figcaption><\/figure>\n<h3><strong>4. Entenda os &#8220;Tr\u00eas n\u00edveis de ROI&#8221;<br \/>\n<\/strong><\/h3>\n<p>Para realmente maximizar o potencial de receita e como o design do parque de surf se encaixa, recomendo olhar para tr\u00eas n\u00edveis (A Piscina, a Praia &amp; Cal\u00e7ad\u00e3o Boardwalk e as comodides adicionais) e como eles correspondem ao seu local de surf em particular. Mantendo-se fiel ao surf, a piscina de ondas \u00e9 obviamente a pe\u00e7a crucial do quebra-cabe\u00e7a e serve como o cora\u00e7\u00e3o da a\u00e7\u00e3o. Tamb\u00e9m cr\u00edtico para a experi\u00eancia de surf, a praia e o cal\u00e7ad\u00e3o atuam como o pr\u00f3ximo n\u00edvel, trazendo consigo o potencial de desenvolvimento da orla. Estando nas imedia\u00e7\u00f5es do break, os surfistas e outros convidados passar\u00e3o muito tempo aqui ap\u00f3s a sess\u00e3o, por isso \u00e9 importante torn\u00e1-la aut\u00eantica e capitalizar o potencial que ela oferece. O \u00faltimo n\u00edvel, as comodidades adicionais, \u00e9 realmente onde o ROI pode ser ilimitado, e isso depende do tipo de desenvolvimento, seus objetivos, or\u00e7amento e quanto espa\u00e7o voc\u00ea est\u00e1 trabalhando. Voc\u00ea pode manter o surf park simples ou realmente alcan\u00e7ar as estrelas. Mas lembre-se da dica n\u00ba 1 \u2013 mantenha-se fiel \u00e0 vibra\u00e7\u00e3o do seu local.<\/p>\n<figure id=\"attachment_1083\" aria-describedby=\"caption-attachment-1083\" style=\"width: 1920px\" class=\"wp-caption alignnone\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-1083 size-full\" src=\"https:\/\/endlesssurf.com\/wp-content\/uploads\/2022\/07\/Endless_Surf_Tiers_of_ROI_Animation_v2.jpg\" alt=\"Infographic of surf park design ROI\" width=\"1920\" height=\"1080\" srcset=\"https:\/\/endlesssurf.com\/wp-content\/uploads\/2022\/07\/Endless_Surf_Tiers_of_ROI_Animation_v2.jpg 1920w, https:\/\/endlesssurf.com\/wp-content\/uploads\/2022\/07\/Endless_Surf_Tiers_of_ROI_Animation_v2-300x169.jpg 300w, https:\/\/endlesssurf.com\/wp-content\/uploads\/2022\/07\/Endless_Surf_Tiers_of_ROI_Animation_v2-1024x576.jpg 1024w\" sizes=\"auto, (max-width: 1920px) 100vw, 1920px\" \/><figcaption id=\"caption-attachment-1083\" class=\"wp-caption-text\">Os tr\u00eas n\u00edveis do ROI<\/figcaption><\/figure>\n<h3><strong>5. Percorra a experi\u00eancia completa do h\u00f3spede do port\u00e3o ao intervalo com os operadores do surf park<br \/>\n<\/strong><\/h3>\n<p><span class=\"TextRun SCXW70800264 BCX9\" lang=\"EN-CA\" xml:lang=\"EN-CA\" data-contrast=\"auto\"><span class=\"NormalTextRun SCXW70800264 BCX9\">Em \u00faltima an\u00e1lise, esta deve ser uma abordagem cont\u00ednua n\u00e3o apenas para o design do surf park, mas tamb\u00e9m para todas as suas decis\u00f5es no processo de desenvolvimento. \u00c9 prov\u00e1vel que estejamos todos em busca do mesmo objetivo\u2026 oferecer experi\u00eancias de surf excepcionais. Meu conselho \u00e9 imaginar a jornada do consumidor \u00a0em toda a sua extens\u00e3o, desde a entrada no port\u00e3o at\u00e9 a remada e o surfe no intervalo at\u00e9 o ponto de encontro e a partida p\u00f3s-sess\u00e3o. Al\u00e9m disso, \u00e9 importante imaginar a experi\u00eancia daqueles que n\u00e3o est\u00e3o surfando, como filhos, c\u00f4njuges e outros convidados. Uma experi\u00eancia completa e especial \u00e9 uma boa maneira de n\u00e3o apenas capturar um grupo demogr\u00e1fico mais amplo, mas tamb\u00e9m incentivar visitas repetidas em v\u00e1rias ocasi\u00f5es. Para ajudar a visualizar essa jornada e garantir que as efici\u00eancias operacionais sejam atendidas, \u00e9 importante incluir os operadores do parque de surf nesta discuss\u00e3o. Ter informa\u00e7\u00f5es adicionais sobre a experi\u00eancia do h\u00f3spede e os processos operacionais \u00e9 crucial para entender as proje\u00e7\u00f5es de efici\u00eancia e retorno.<\/span><\/span><span class=\"EOP SCXW70800264 BCX9\" data-ccp-props=\"{&quot;201341983&quot;:0,&quot;335559739&quot;:160,&quot;335559740&quot;:259}\">\u00a0<\/span><\/p>\n<figure id=\"attachment_1096\" aria-describedby=\"caption-attachment-1096\" style=\"width: 726px\" class=\"wp-caption alignnone\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-1096 size-full\" src=\"https:\/\/endlesssurf.com\/wp-content\/uploads\/2022\/07\/C0A57304-6FD5-4986-B0D4-8141B0BD8503.jpg\" alt=\"surf park design sketches\" width=\"726\" height=\"407\" srcset=\"https:\/\/endlesssurf.com\/wp-content\/uploads\/2022\/07\/C0A57304-6FD5-4986-B0D4-8141B0BD8503.jpg 726w, https:\/\/endlesssurf.com\/wp-content\/uploads\/2022\/07\/C0A57304-6FD5-4986-B0D4-8141B0BD8503-300x168.jpg 300w\" sizes=\"auto, (max-width: 726px) 100vw, 726px\" \/><figcaption id=\"caption-attachment-1096\" class=\"wp-caption-text\">Como voc\u00ea ja escutou, o design do local \u00e9 uma verdadeira arte.<\/figcaption><\/figure>\n<p>Se voc\u00ea est\u00e1 na fase de design do surf park, manter essas dicas e princ\u00edpios b\u00e1sicos em mente quando se trata de design do local pode ser uma \u00f3tima maneira de permanecer fiel ao seu objetivo de oferecer experi\u00eancias inesquec\u00edveis para surfistas e convidados.<\/p>\n<h4><em>Interessado em mais dicas de design de locais para o seu projeto ou deseja aproveitar a experi\u00eancia de Anthony? Entre em contato conosco para marcar um hor\u00e1rio para conversar sobre a vis\u00e3o e os desafios do seu projeto.<\/em><\/h4>\n<script>\nvar gform;gform||(document.addEventListener(\"gform_main_scripts_loaded\",function(){gform.scriptsLoaded=!0}),document.addEventListener(\"gform\/theme\/scripts_loaded\",function(){gform.themeScriptsLoaded=!0}),window.addEventListener(\"DOMContentLoaded\",function(){gform.domLoaded=!0}),gform={domLoaded:!1,scriptsLoaded:!1,themeScriptsLoaded:!1,isFormEditor:()=>\"function\"==typeof InitializeEditor,callIfLoaded:function(o){return!(!gform.domLoaded||!gform.scriptsLoaded||!gform.themeScriptsLoaded&&!gform.isFormEditor()||(gform.isFormEditor()&&console.warn(\"The use of gform.initializeOnLoaded() is deprecated in the form editor context and will be removed in Gravity Forms 3.1.\"),o(),0))},initializeOnLoaded:function(o){gform.callIfLoaded(o)||(document.addEventListener(\"gform_main_scripts_loaded\",()=>{gform.scriptsLoaded=!0,gform.callIfLoaded(o)}),document.addEventListener(\"gform\/theme\/scripts_loaded\",()=>{gform.themeScriptsLoaded=!0,gform.callIfLoaded(o)}),window.addEventListener(\"DOMContentLoaded\",()=>{gform.domLoaded=!0,gform.callIfLoaded(o)}))},hooks:{action:{},filter:{}},addAction:function(o,r,e,t){gform.addHook(\"action\",o,r,e,t)},addFilter:function(o,r,e,t){gform.addHook(\"filter\",o,r,e,t)},doAction:function(o){gform.doHook(\"action\",o,arguments)},applyFilters:function(o){return gform.doHook(\"filter\",o,arguments)},removeAction:function(o,r){gform.removeHook(\"action\",o,r)},removeFilter:function(o,r,e){gform.removeHook(\"filter\",o,r,e)},addHook:function(o,r,e,t,n){null==gform.hooks[o][r]&&(gform.hooks[o][r]=[]);var d=gform.hooks[o][r];null==n&&(n=r+\"_\"+d.length),gform.hooks[o][r].push({tag:n,callable:e,priority:t=null==t?10:t})},doHook:function(r,o,e){var t;if(e=Array.prototype.slice.call(e,1),null!=gform.hooks[r][o]&&((o=gform.hooks[r][o]).sort(function(o,r){return o.priority-r.priority}),o.forEach(function(o){\"function\"!=typeof(t=o.callable)&&(t=window[t]),\"action\"==r?t.apply(null,e):e[0]=t.apply(null,e)})),\"filter\"==r)return e[0]},removeHook:function(o,r,t,n){var e;null!=gform.hooks[o][r]&&(e=(e=gform.hooks[o][r]).filter(function(o,r,e){return!!(null!=n&&n!=o.tag||null!=t&&t!=o.priority)}),gform.hooks[o][r]=e)}});\n<\/script>\n\n                <div class='gf_browser_gecko gform_wrapper gform_legacy_markup_wrapper gform-theme--no-framework' data-form-theme='legacy' data-form-index='0' id='gform_wrapper_1' >\n                        <div class='gform_heading'>\n                            <p class='gform_description'><\/p>\n                        <\/div><form method='post' enctype='multipart\/form-data'  id='gform_1'  action='\/br\/wp-json\/wp\/v2\/posts\/1865' data-formid='1' novalidate>\n                        <div class='gform-body gform_body'><ul id='gform_fields_1' class='gform_fields top_label form_sublabel_below description_below validation_below'><li id=\"field_1_1\" class=\"gfield gfield--type-text gfield--input-type-text gf_left_half gfield_contains_required field_sublabel_below gfield--no-description field_description_below field_validation_below gfield_visibility_visible\"  ><label class='gfield_label gform-field-label' for='input_1_1'>Nome<span class=\"gfield_required\"><span class=\"gfield_required gfield_required_asterisk\">*<\/span><\/span><\/label><div class='ginput_container ginput_container_text'><input name='input_1' id='input_1_1' type='text' value='' class='large'    placeholder='Nome' aria-required=\"true\" aria-invalid=\"false\"   \/ data-name=\"FirstName\"><\/div><\/li><li id=\"field_1_2\" class=\"gfield gfield--type-text gfield--input-type-text gf_right_half gfield_contains_required field_sublabel_below gfield--no-description field_description_below field_validation_below gfield_visibility_visible\"  ><label class='gfield_label gform-field-label' for='input_1_2'>Sobrenome<span class=\"gfield_required\"><span class=\"gfield_required gfield_required_asterisk\">*<\/span><\/span><\/label><div class='ginput_container ginput_container_text'><input name='input_2' id='input_1_2' type='text' value='' class='large'    placeholder='Sobrenome' aria-required=\"true\" aria-invalid=\"false\"   \/ data-name=\"LastName\"><\/div><\/li><li id=\"field_1_3\" class=\"gfield gfield--type-email gfield--input-type-email gf_left_half gfield_contains_required field_sublabel_below gfield--no-description field_description_below field_validation_below gfield_visibility_visible\"  ><label class='gfield_label gform-field-label' for='input_1_3'>Email<span class=\"gfield_required\"><span class=\"gfield_required gfield_required_asterisk\">*<\/span><\/span><\/label><div class='ginput_container ginput_container_email'>\n                            <input name='input_3' id='input_1_3' type='email' value='' class='large'   placeholder='Email' aria-required=\"true\" aria-invalid=\"false\"  \/ data-name=\"EMailAddress1\">\n                        <\/div><\/li><li id=\"field_1_4\" class=\"gfield gfield--type-phone gfield--input-type-phone gf_right_half field_sublabel_below gfield--no-description field_description_below field_validation_below gfield_visibility_visible\"  ><label class='gfield_label gform-field-label' for='input_1_4'>Telefone<\/label><div class='ginput_container ginput_container_phone'><input name='input_4' id='input_1_4' type='tel' value='' class='large'  placeholder='Telefone'  aria-invalid=\"false\"   \/><\/div><\/li><li id=\"field_1_11\" class=\"gfield gfield--type-select gfield--input-type-select gfield_contains_required field_sublabel_below gfield--no-description field_description_below field_validation_below gfield_visibility_visible\"  ><label class='gfield_label gform-field-label' for='input_1_11'>Pa\u00eds<span class=\"gfield_required\"><span class=\"gfield_required gfield_required_asterisk\">*<\/span><\/span><\/label><div class='ginput_container ginput_container_select'><select name='input_11' id='input_1_11' class='medium gfield_select'    aria-required=\"true\" aria-invalid=\"false\"  data-name=\"ww_CountryLookup\"><option value='' selected='selected' class='gf_placeholder'>Selecione o seu pa\u00eds<\/option><option value='58cb0fc9-0952-e711-815f-e0071b715b51' >United States<\/option><option value='fcc90fc9-0952-e711-815f-e0071b715b51' >Canada<\/option><option value='b8c90fc9-0952-e711-815f-e0071b715b51' >Abkhazia<\/option><option value='bac90fc9-0952-e711-815f-e0071b715b51' >Afghanistan<\/option><option value='bcc90fc9-0952-e711-815f-e0071b715b51' >Albania<\/option><option value='bec90fc9-0952-e711-815f-e0071b715b51' >Algeria<\/option><option value='c0c90fc9-0952-e711-815f-e0071b715b51' >Andorra<\/option><option value='c2c90fc9-0952-e711-815f-e0071b715b51' >Angola<\/option><option value='c4c90fc9-0952-e711-815f-e0071b715b51' >Antigua and Barbuda<\/option><option value='c6c90fc9-0952-e711-815f-e0071b715b51' >Argentina<\/option><option value='c8c90fc9-0952-e711-815f-e0071b715b51' >Armenia<\/option><option value='cac90fc9-0952-e711-815f-e0071b715b51' >Aruba<\/option><option value='ccc90fc9-0952-e711-815f-e0071b715b51' >Australia<\/option><option value='cec90fc9-0952-e711-815f-e0071b715b51' >Austria<\/option><option value='d0c90fc9-0952-e711-815f-e0071b715b51' >Azerbaijan<\/option><option value='d2c90fc9-0952-e711-815f-e0071b715b51' >Bahamas<\/option><option value='d4c90fc9-0952-e711-815f-e0071b715b51' >Bahrain<\/option><option value='d6c90fc9-0952-e711-815f-e0071b715b51' >Bangladesh<\/option><option value='d8c90fc9-0952-e711-815f-e0071b715b51' >Barbados<\/option><option value='dac90fc9-0952-e711-815f-e0071b715b51' >Belarus<\/option><option value='dcc90fc9-0952-e711-815f-e0071b715b51' >Belgium<\/option><option value='dec90fc9-0952-e711-815f-e0071b715b51' >Belize<\/option><option value='e0c90fc9-0952-e711-815f-e0071b715b51' >Benin<\/option><option value='e2c90fc9-0952-e711-815f-e0071b715b51' >Bermuda<\/option><option value='e4c90fc9-0952-e711-815f-e0071b715b51' >Bhutan<\/option><option value='e6c90fc9-0952-e711-815f-e0071b715b51' >Bolivia<\/option><option value='e8c90fc9-0952-e711-815f-e0071b715b51' >Bosnia and Herzegovina<\/option><option value='eac90fc9-0952-e711-815f-e0071b715b51' >Botswana<\/option><option value='ecc90fc9-0952-e711-815f-e0071b715b51' >Brazil<\/option><option value='eec90fc9-0952-e711-815f-e0071b715b51' >Brunei<\/option><option value='f0c90fc9-0952-e711-815f-e0071b715b51' >Bulgaria<\/option><option value='f2c90fc9-0952-e711-815f-e0071b715b51' >Burkina Faso<\/option><option value='f4c90fc9-0952-e711-815f-e0071b715b51' >Burma (Myanmar)<\/option><option value='f6c90fc9-0952-e711-815f-e0071b715b51' >Burundi<\/option><option value='f8c90fc9-0952-e711-815f-e0071b715b51' >Cambodia<\/option><option value='fac90fc9-0952-e711-815f-e0071b715b51' >Cameroon<\/option><option value='fec90fc9-0952-e711-815f-e0071b715b51' >Cape Verde<\/option><option value='00ca0fc9-0952-e711-815f-e0071b715b51' >Central African Republic<\/option><option value='02ca0fc9-0952-e711-815f-e0071b715b51' >Chad<\/option><option value='04ca0fc9-0952-e711-815f-e0071b715b51' >Chile<\/option><option value='06ca0fc9-0952-e711-815f-e0071b715b51' >China<\/option><option value='08ca0fc9-0952-e711-815f-e0071b715b51' >Colombia<\/option><option value='0aca0fc9-0952-e711-815f-e0071b715b51' >Comoros<\/option><option value='0cca0fc9-0952-e711-815f-e0071b715b51' >Congo<\/option><option value='0eca0fc9-0952-e711-815f-e0071b715b51' >Cook Islands<\/option><option value='10ca0fc9-0952-e711-815f-e0071b715b51' >Costa Rica<\/option><option value='12ca0fc9-0952-e711-815f-e0071b715b51' >Croatia<\/option><option value='14ca0fc9-0952-e711-815f-e0071b715b51' >Cuba<\/option><option value='16ca0fc9-0952-e711-815f-e0071b715b51' >Curacao<\/option><option value='18ca0fc9-0952-e711-815f-e0071b715b51' >Cyprus<\/option><option value='1aca0fc9-0952-e711-815f-e0071b715b51' >Czech Republic<\/option><option value='1cca0fc9-0952-e711-815f-e0071b715b51' >Denmark<\/option><option value='1eca0fc9-0952-e711-815f-e0071b715b51' >Djibouti<\/option><option value='20ca0fc9-0952-e711-815f-e0071b715b51' >Dominica<\/option><option value='22ca0fc9-0952-e711-815f-e0071b715b51' >Dominican Republic<\/option><option value='24ca0fc9-0952-e711-815f-e0071b715b51' >East Timor<\/option><option value='26ca0fc9-0952-e711-815f-e0071b715b51' >Ecuador<\/option><option value='28ca0fc9-0952-e711-815f-e0071b715b51' >Egypt<\/option><option value='2aca0fc9-0952-e711-815f-e0071b715b51' >El Salvador<\/option><option value='2cca0fc9-0952-e711-815f-e0071b715b51' >Equatorial Guinea<\/option><option value='2eca0fc9-0952-e711-815f-e0071b715b51' >Eritrea<\/option><option value='30ca0fc9-0952-e711-815f-e0071b715b51' >Estonia<\/option><option value='32ca0fc9-0952-e711-815f-e0071b715b51' >Ethiopia<\/option><option value='34ca0fc9-0952-e711-815f-e0071b715b51' >Fiji<\/option><option value='36ca0fc9-0952-e711-815f-e0071b715b51' >Finland<\/option><option value='38ca0fc9-0952-e711-815f-e0071b715b51' >France<\/option><option value='3aca0fc9-0952-e711-815f-e0071b715b51' >Gabon<\/option><option value='3cca0fc9-0952-e711-815f-e0071b715b51' >Gambia<\/option><option value='3eca0fc9-0952-e711-815f-e0071b715b51' >Georgia<\/option><option value='40ca0fc9-0952-e711-815f-e0071b715b51' >Germany<\/option><option value='42ca0fc9-0952-e711-815f-e0071b715b51' >Ghana<\/option><option value='44ca0fc9-0952-e711-815f-e0071b715b51' >Grand Caymen Islands<\/option><option value='46ca0fc9-0952-e711-815f-e0071b715b51' >Greece<\/option><option value='48ca0fc9-0952-e711-815f-e0071b715b51' >Grenada<\/option><option value='4aca0fc9-0952-e711-815f-e0071b715b51' >Guam<\/option><option value='4cca0fc9-0952-e711-815f-e0071b715b51' >Guatemala<\/option><option value='4eca0fc9-0952-e711-815f-e0071b715b51' >Guinea<\/option><option value='50ca0fc9-0952-e711-815f-e0071b715b51' >Guinea-Bissau<\/option><option value='52ca0fc9-0952-e711-815f-e0071b715b51' >Guyana<\/option><option value='54ca0fc9-0952-e711-815f-e0071b715b51' >Haiti<\/option><option value='56ca0fc9-0952-e711-815f-e0071b715b51' >Honduras<\/option><option value='58ca0fc9-0952-e711-815f-e0071b715b51' >Hong Kong<\/option><option value='5aca0fc9-0952-e711-815f-e0071b715b51' >Hungary<\/option><option value='5cca0fc9-0952-e711-815f-e0071b715b51' >Iceland<\/option><option value='5eca0fc9-0952-e711-815f-e0071b715b51' >India<\/option><option value='60ca0fc9-0952-e711-815f-e0071b715b51' >Indonesia<\/option><option value='62ca0fc9-0952-e711-815f-e0071b715b51' >Iran<\/option><option value='64ca0fc9-0952-e711-815f-e0071b715b51' >Iraq<\/option><option value='66ca0fc9-0952-e711-815f-e0071b715b51' >Ireland<\/option><option value='68ca0fc9-0952-e711-815f-e0071b715b51' >Israel<\/option><option value='6aca0fc9-0952-e711-815f-e0071b715b51' >Italy<\/option><option value='6cca0fc9-0952-e711-815f-e0071b715b51' >Ivory Coast<\/option><option value='6eca0fc9-0952-e711-815f-e0071b715b51' >Jamaica<\/option><option value='70ca0fc9-0952-e711-815f-e0071b715b51' >Japan<\/option><option value='72ca0fc9-0952-e711-815f-e0071b715b51' >Jordan<\/option><option value='74ca0fc9-0952-e711-815f-e0071b715b51' >Kazakhstan<\/option><option value='76ca0fc9-0952-e711-815f-e0071b715b51' >Kenya<\/option><option value='78ca0fc9-0952-e711-815f-e0071b715b51' >Kiribati<\/option><option value='7aca0fc9-0952-e711-815f-e0071b715b51' >Korea<\/option><option value='7eca0fc9-0952-e711-815f-e0071b715b51' >Kosovo<\/option><option value='80ca0fc9-0952-e711-815f-e0071b715b51' >Kuwait<\/option><option value='82ca0fc9-0952-e711-815f-e0071b715b51' >Kyrgyzstan<\/option><option value='84ca0fc9-0952-e711-815f-e0071b715b51' >Laos<\/option><option value='86ca0fc9-0952-e711-815f-e0071b715b51' >Latvia<\/option><option value='88ca0fc9-0952-e711-815f-e0071b715b51' >Lebanon<\/option><option value='8aca0fc9-0952-e711-815f-e0071b715b51' >Lesotho<\/option><option value='8cca0fc9-0952-e711-815f-e0071b715b51' >Liberia<\/option><option value='8eca0fc9-0952-e711-815f-e0071b715b51' >Libya<\/option><option value='90ca0fc9-0952-e711-815f-e0071b715b51' >Liechtenstein<\/option><option value='92ca0fc9-0952-e711-815f-e0071b715b51' >Lithuania<\/option><option value='94ca0fc9-0952-e711-815f-e0071b715b51' >Luxembourg<\/option><option value='96ca0fc9-0952-e711-815f-e0071b715b51' >Macau<\/option><option value='98ca0fc9-0952-e711-815f-e0071b715b51' >Macedonia<\/option><option value='9aca0fc9-0952-e711-815f-e0071b715b51' >Madagascar<\/option><option value='9cca0fc9-0952-e711-815f-e0071b715b51' >Malawi<\/option><option value='9eca0fc9-0952-e711-815f-e0071b715b51' >Malaysia<\/option><option value='a0ca0fc9-0952-e711-815f-e0071b715b51' >Maldives<\/option><option value='a2ca0fc9-0952-e711-815f-e0071b715b51' >Mali<\/option><option value='a4ca0fc9-0952-e711-815f-e0071b715b51' >Malta<\/option><option value='a7ca0fc9-0952-e711-815f-e0071b715b51' >Marshall Islands<\/option><option value='a9ca0fc9-0952-e711-815f-e0071b715b51' >Mauritania<\/option><option value='abca0fc9-0952-e711-815f-e0071b715b51' >Mauritius<\/option><option value='adca0fc9-0952-e711-815f-e0071b715b51' >Mexico<\/option><option value='afca0fc9-0952-e711-815f-e0071b715b51' >Micronesia<\/option><option value='b1ca0fc9-0952-e711-815f-e0071b715b51' >Moldova<\/option><option value='b3ca0fc9-0952-e711-815f-e0071b715b51' >Monaco<\/option><option value='b5ca0fc9-0952-e711-815f-e0071b715b51' >Mongolia<\/option><option value='b7ca0fc9-0952-e711-815f-e0071b715b51' >Montenegro<\/option><option value='b9ca0fc9-0952-e711-815f-e0071b715b51' >Morocco<\/option><option value='bbca0fc9-0952-e711-815f-e0071b715b51' >Mozambique<\/option><option value='bdca0fc9-0952-e711-815f-e0071b715b51' >Myanmar (Burma)<\/option><option value='bfca0fc9-0952-e711-815f-e0071b715b51' >Nagorno-Karabakh<\/option><option value='c1ca0fc9-0952-e711-815f-e0071b715b51' >Namibia<\/option><option value='c3ca0fc9-0952-e711-815f-e0071b715b51' >Nauru<\/option><option value='c5ca0fc9-0952-e711-815f-e0071b715b51' >Nepal<\/option><option value='c7ca0fc9-0952-e711-815f-e0071b715b51' >Netherlands<\/option><option value='c9ca0fc9-0952-e711-815f-e0071b715b51' >Netherlands Antilles<\/option><option value='cbca0fc9-0952-e711-815f-e0071b715b51' >New Zealand<\/option><option value='cdca0fc9-0952-e711-815f-e0071b715b51' >Nicaragua<\/option><option value='cfca0fc9-0952-e711-815f-e0071b715b51' >Niger<\/option><option value='d1ca0fc9-0952-e711-815f-e0071b715b51' >Nigeria<\/option><option value='d3ca0fc9-0952-e711-815f-e0071b715b51' >Niue<\/option><option value='d5ca0fc9-0952-e711-815f-e0071b715b51' >Northern Cyprus<\/option><option value='d7ca0fc9-0952-e711-815f-e0071b715b51' >Norway<\/option><option value='d9ca0fc9-0952-e711-815f-e0071b715b51' >Oman<\/option><option value='dbca0fc9-0952-e711-815f-e0071b715b51' >Pakistan<\/option><option value='ddca0fc9-0952-e711-815f-e0071b715b51' >Palau<\/option><option value='dfca0fc9-0952-e711-815f-e0071b715b51' >Palestine<\/option><option value='e1ca0fc9-0952-e711-815f-e0071b715b51' >Panama<\/option><option value='e3ca0fc9-0952-e711-815f-e0071b715b51' >Papua New Guinea<\/option><option value='e5ca0fc9-0952-e711-815f-e0071b715b51' >Paraguay<\/option><option value='e7ca0fc9-0952-e711-815f-e0071b715b51' >Peru<\/option><option value='e9ca0fc9-0952-e711-815f-e0071b715b51' >Philippines<\/option><option value='ebca0fc9-0952-e711-815f-e0071b715b51' >Poland<\/option><option value='edca0fc9-0952-e711-815f-e0071b715b51' >Portugal<\/option><option value='efca0fc9-0952-e711-815f-e0071b715b51' >Puerto Rico<\/option><option value='f1ca0fc9-0952-e711-815f-e0071b715b51' >Qatar<\/option><option value='f3ca0fc9-0952-e711-815f-e0071b715b51' >Romania<\/option><option value='f5ca0fc9-0952-e711-815f-e0071b715b51' >Russia<\/option><option value='f7ca0fc9-0952-e711-815f-e0071b715b51' >Rwanda<\/option><option value='f9ca0fc9-0952-e711-815f-e0071b715b51' >Sahrawi Arab Democratic Republic<\/option><option value='fbca0fc9-0952-e711-815f-e0071b715b51' >Saint Kitts and Nevis<\/option><option value='fdca0fc9-0952-e711-815f-e0071b715b51' >Saint Lucia<\/option><option value='ffca0fc9-0952-e711-815f-e0071b715b51' >Saint Martin<\/option><option value='01cb0fc9-0952-e711-815f-e0071b715b51' >Samoa<\/option><option value='03cb0fc9-0952-e711-815f-e0071b715b51' >San Marino<\/option><option value='05cb0fc9-0952-e711-815f-e0071b715b51' >S\u00e3o Tom\u00e9 and Pr\u00edncipe<\/option><option value='07cb0fc9-0952-e711-815f-e0071b715b51' >Saudi Arabia<\/option><option value='09cb0fc9-0952-e711-815f-e0071b715b51' >Senegal<\/option><option value='0bcb0fc9-0952-e711-815f-e0071b715b51' >Serbia<\/option><option value='0dcb0fc9-0952-e711-815f-e0071b715b51' >Seychelles<\/option><option value='0fcb0fc9-0952-e711-815f-e0071b715b51' >Sierra Leone<\/option><option value='11cb0fc9-0952-e711-815f-e0071b715b51' >Singapore<\/option><option value='13cb0fc9-0952-e711-815f-e0071b715b51' >Slovakia<\/option><option value='15cb0fc9-0952-e711-815f-e0071b715b51' >Slovenia<\/option><option value='17cb0fc9-0952-e711-815f-e0071b715b51' >Solomon Islands<\/option><option value='1acb0fc9-0952-e711-815f-e0071b715b51' >Somalia<\/option><option value='1ccb0fc9-0952-e711-815f-e0071b715b51' >Somaliland<\/option><option value='1ecb0fc9-0952-e711-815f-e0071b715b51' >South Africa<\/option><option value='20cb0fc9-0952-e711-815f-e0071b715b51' >South Ossetia<\/option><option value='22cb0fc9-0952-e711-815f-e0071b715b51' >Spain<\/option><option value='24cb0fc9-0952-e711-815f-e0071b715b51' >Sri Lanka<\/option><option value='26cb0fc9-0952-e711-815f-e0071b715b51' >St. Vincent and the Grenadines<\/option><option value='28cb0fc9-0952-e711-815f-e0071b715b51' >Sudan<\/option><option value='2acb0fc9-0952-e711-815f-e0071b715b51' >Suriname<\/option><option value='2ccb0fc9-0952-e711-815f-e0071b715b51' >Swaziland<\/option><option value='2ecb0fc9-0952-e711-815f-e0071b715b51' >Sweden<\/option><option value='30cb0fc9-0952-e711-815f-e0071b715b51' >Switzerland<\/option><option value='32cb0fc9-0952-e711-815f-e0071b715b51' >Syria<\/option><option value='34cb0fc9-0952-e711-815f-e0071b715b51' >Tahiti<\/option><option value='36cb0fc9-0952-e711-815f-e0071b715b51' >Taiwan<\/option><option value='38cb0fc9-0952-e711-815f-e0071b715b51' >Tajikistan<\/option><option value='3acb0fc9-0952-e711-815f-e0071b715b51' >Tanzania<\/option><option value='3ccb0fc9-0952-e711-815f-e0071b715b51' >Thailand<\/option><option value='3ecb0fc9-0952-e711-815f-e0071b715b51' >Timor-Leste \/ East Timor<\/option><option value='40cb0fc9-0952-e711-815f-e0071b715b51' >Togo<\/option><option value='42cb0fc9-0952-e711-815f-e0071b715b51' >Tonga<\/option><option value='44cb0fc9-0952-e711-815f-e0071b715b51' >Trinidad and Tobago<\/option><option value='46cb0fc9-0952-e711-815f-e0071b715b51' >Tunisia<\/option><option value='48cb0fc9-0952-e711-815f-e0071b715b51' >Turkey<\/option><option value='4acb0fc9-0952-e711-815f-e0071b715b51' >Turkmenistan<\/option><option value='4ccb0fc9-0952-e711-815f-e0071b715b51' >Turks and Caicos<\/option><option value='4ecb0fc9-0952-e711-815f-e0071b715b51' >Tuvalu<\/option><option value='50cb0fc9-0952-e711-815f-e0071b715b51' >Uganda<\/option><option value='52cb0fc9-0952-e711-815f-e0071b715b51' >Ukraine<\/option><option value='54cb0fc9-0952-e711-815f-e0071b715b51' >United Arab Emirates<\/option><option value='56cb0fc9-0952-e711-815f-e0071b715b51' >United Kingdom<\/option><option value='5acb0fc9-0952-e711-815f-e0071b715b51' >Uruguay<\/option><option value='5ccb0fc9-0952-e711-815f-e0071b715b51' >Uzbekistan<\/option><option value='5ecb0fc9-0952-e711-815f-e0071b715b51' >Vanuatu<\/option><option value='60cb0fc9-0952-e711-815f-e0071b715b51' >Vatican City<\/option><option value='62cb0fc9-0952-e711-815f-e0071b715b51' >Venezuela<\/option><option value='64cb0fc9-0952-e711-815f-e0071b715b51' >Vietnam<\/option><option value='66cb0fc9-0952-e711-815f-e0071b715b51' >Virgin Islands<\/option><option value='68cb0fc9-0952-e711-815f-e0071b715b51' >Yemen<\/option><option value='6acb0fc9-0952-e711-815f-e0071b715b51' >Zambia<\/option><option value='6ccb0fc9-0952-e711-815f-e0071b715b51' >Zimbabwe<\/option><\/select><\/div><\/li><li id=\"field_1_12\" class=\"gfield gfield--type-select gfield--input-type-select gf_left_half gfield_contains_required field_sublabel_below gfield--no-description field_description_below field_validation_below gfield_visibility_visible\"  ><label class='gfield_label gform-field-label' for='input_1_12'>Cargo<span class=\"gfield_required\"><span class=\"gfield_required gfield_required_asterisk\">*<\/span><\/span><\/label><div class='ginput_container ginput_container_select'><select name='input_12' id='input_1_12' class='medium gfield_select'    aria-required=\"true\" aria-invalid=\"false\"  data-name=\"JobTitle\"><option value='' selected='selected' class='gf_placeholder'>Please Select<\/option><option value='Owner' selected='selected'>Owner<\/option><option value='Senior Executive' >Senior Executive<\/option><option value='General Manager' >General Manager<\/option><option value='Operations' >Operations<\/option><option value='Purchasing' >Purchasing<\/option><option value='Architect\/Designer' >Architect\/Designer<\/option><option value='Marketing' >Marketing<\/option><option value='Developer' >Developer<\/option><option value='General Contractor' >General Contractor<\/option><\/select><\/div><\/li><li id=\"field_1_6\" class=\"gfield gfield--type-text gfield--input-type-text gf_right_half gfield_contains_required field_sublabel_below gfield--no-description field_description_below field_validation_below gfield_visibility_visible\"  ><label class='gfield_label gform-field-label' for='input_1_6'>Empresa<span class=\"gfield_required\"><span class=\"gfield_required gfield_required_asterisk\">*<\/span><\/span><\/label><div class='ginput_container ginput_container_text'><input name='input_6' id='input_1_6' type='text' value='' class='large'    placeholder='Empresa' aria-required=\"true\" aria-invalid=\"false\"   \/ data-name=\"CompanyName\"><\/div><\/li><li id=\"field_1_13\" class=\"gfield gfield--type-select gfield--input-type-select gfield_contains_required field_sublabel_below gfield--no-description field_description_below field_validation_below gfield_visibility_visible\"  ><label class='gfield_label gform-field-label' for='input_1_13'>Como ficou sabendo sobre n\u00f3s?<span class=\"gfield_required\"><span class=\"gfield_required gfield_required_asterisk\">*<\/span><\/span><\/label><div class='ginput_container ginput_container_select'><select name='input_13' id='input_1_13' class='medium gfield_select'    aria-required=\"true\" aria-invalid=\"false\"  data-name=\"ww_Howdidyouhearaboutus\"><option value='' selected='selected' class='gf_placeholder'>Please Select<\/option><option value='266920000' selected='selected'>Internet Search \/ Social Media<\/option><option value='266920001' >Referral \/ Word of Mouth<\/option><option value='266920002' >Magazine Ad or Article<\/option><option value='266920003' >Tradeshow \/ Conference<\/option><option value='266920008' >I tried one of your products and loved it!<\/option><\/select><\/div><\/li><li id=\"field_1_7\" class=\"gfield gfield--type-textarea gfield--input-type-textarea gfield_contains_required field_sublabel_below gfield--no-description field_description_below field_validation_below gfield_visibility_visible\"  ><label class='gfield_label gform-field-label' for='input_1_7'>Como Podemos te ajudar?<span class=\"gfield_required\"><span class=\"gfield_required gfield_required_asterisk\">*<\/span><\/span><\/label><div class='ginput_container ginput_container_textarea'><textarea name='input_7' id='input_1_7' class='textarea medium'    placeholder='Are there any other details you can share to help us respond to your inquiry.' aria-required=\"true\" aria-invalid=\"false\"   rows='10' cols='50' data-name=\"Description\"><\/textarea><\/div><\/li><li id=\"field_1_8\" class=\"gfield gfield--type-checkbox gfield--type-choice gfield--input-type-checkbox field_sublabel_below gfield--has-description field_description_below field_validation_below gfield_visibility_visible\"  ><label class='gfield_label gform-field-label gfield_label_before_complex' >Fique por dentro<\/label><div class='ginput_container ginput_container_checkbox'><ul class='gfield_checkbox' id='input_1_8'><li class='gchoice gchoice_1_8_1'>\n\t\t\t\t\t\t\t\t<input class='gfield-choice-input' name='input_8.1' type='checkbox'  value='true' checked='checked' id='choice_1_8_1'   aria-describedby=\"gfield_description_1_8\"\/ data-name=\"ww_EmailOptIn\">\n\t\t\t\t\t\t\t\t<label for='choice_1_8_1' id='label_1_8_1' class='gform-field-label gform-field-label--type-inline'>Sim. Quero inscrever!<\/label>\n\t\t\t\t\t\t\t<\/li><\/ul><\/div><div class='gfield_description' id='gfield_description_1_8'>Inscreva-se para receber as \u00faltimas not\u00edcias, atualiza\u00e7\u00f5es de projetos e inova\u00e7\u00f5es do mundo do surf indoor. *Ao marcar esta caixa, voc\u00ea concorda em receber e-mails de marketing da Endless Surf. Voc\u00ea pode revogar seu consentimento para receber e-mails a qualquer momento usando o link Cancelar inscri\u00e7\u00e3o encontrado na parte inferior de cada e-mail.<\/div><\/li><li id=\"field_1_10\" class=\"gfield gfield--type-hidden gfield--input-type-hidden gform_hidden field_sublabel_below gfield--no-description field_description_below field_validation_below gfield_visibility_visible\"  ><div class='ginput_container ginput_container_text'><input name='input_10' id='input_1_10' type='hidden' class='gform_hidden'  aria-invalid=\"false\" value='266920014' \/ data-name=\"LeadSourceCode\"><\/div><\/li><li id=\"field_1_14\" class=\"gfield gfield--type-hidden gfield--input-type-hidden gform_hidden field_sublabel_below gfield--no-description field_description_below field_validation_below gfield_visibility_visible\"  ><div class='ginput_container ginput_container_text'><input name='input_14' id='input_1_14' type='hidden' class='gform_hidden'  aria-invalid=\"false\" value='ES Contact Form' \/ data-name=\"ww_webcampaign\"><\/div><\/li><li id=\"field_1_15\" class=\"gfield gfield--type-hidden gfield--input-type-hidden gform_hidden field_sublabel_below gfield--no-description field_description_below field_validation_below gfield_visibility_visible\"  ><div class='ginput_container ginput_container_text'><input name='input_15' id='input_1_15' type='hidden' class='gform_hidden'  aria-invalid=\"false\" value='Endless Surf General' \/ data-name=\"ww_newsletter\"><\/div><\/li><li id=\"field_1_16\" class=\"gfield gfield--type-hidden gfield--input-type-hidden gform_hidden field_sublabel_below gfield--no-description field_description_below field_validation_below gfield_visibility_visible\"  ><div class='ginput_container ginput_container_text'><input name='input_16' id='input_1_16' type='hidden' class='gform_hidden'  aria-invalid=\"false\" value='Regular' \/ data-name=\"ww_leadflag\"><\/div><\/li><li id=\"field_1_17\" class=\"gfield gfield--type-hidden gfield--input-type-hidden gform_hidden field_sublabel_below gfield--no-description field_description_below field_validation_below gfield_visibility_visible\"  ><div class='ginput_container ginput_container_text'><input name='input_17' id='input_1_17' type='hidden' class='gform_hidden'  aria-invalid=\"false\" value='Endless Surf Contact Us Form' \/ data-name=\"Subject\"><\/div><\/li><li id=\"field_1_18\" class=\"gfield gfield--type-hidden gfield--input-type-hidden gform_hidden field_sublabel_below gfield--no-description field_description_below field_validation_below gfield_visibility_visible\"  ><div class='ginput_container ginput_container_text'><input name='input_18' id='input_1_18' type='hidden' class='gform_hidden'  aria-invalid=\"false\" value='' \/ data-name=\"utm_source\"><\/div><\/li><li id=\"field_1_19\" class=\"gfield gfield--type-hidden gfield--input-type-hidden gform_hidden field_sublabel_below gfield--no-description field_description_below field_validation_below gfield_visibility_visible\"  ><div class='ginput_container ginput_container_text'><input name='input_19' id='input_1_19' type='hidden' class='gform_hidden'  aria-invalid=\"false\" value='' \/ data-name=\"utm_medium\"><\/div><\/li><li id=\"field_1_20\" class=\"gfield gfield--type-hidden gfield--input-type-hidden gform_hidden field_sublabel_below gfield--no-description field_description_below field_validation_below gfield_visibility_visible\"  ><div class='ginput_container ginput_container_text'><input name='input_20' id='input_1_20' type='hidden' class='gform_hidden'  aria-invalid=\"false\" value='' \/ data-name=\"utm_campaign\"><\/div><\/li><\/ul><\/div>\n        <div class='gform-footer gform_footer top_label'> <input type='submit' id='gform_submit_button_1' class='gform_button button' onclick='gform.submission.handleButtonClick(this);' data-submission-type='submit' value='Submit'  \/> \n            <input type='hidden' class='gform_hidden' name='gform_submission_method' data-js='gform_submission_method_1' value='postback' \/>\n            <input type='hidden' class='gform_hidden' name='gform_theme' data-js='gform_theme_1' id='gform_theme_1' value='legacy' \/>\n            <input type='hidden' class='gform_hidden' name='gform_style_settings' data-js='gform_style_settings_1' id='gform_style_settings_1' value='[]' \/>\n            <input type='hidden' class='gform_hidden' name='is_submit_1' value='1' \/>\n            <input type='hidden' class='gform_hidden' name='gform_submit' value='1' \/>\n            \n            <input type='hidden' class='gform_hidden' name='gform_currency' data-currency='USD' value='IEU6ZJrMrkbmmVP8rISUJbOOHuMNRy5757XFfjQxqVe\/YjjMzFL6tvTGsFmxwBVvZ0jm8PZ\/lLuU344bF1iVwcdwHDOa9dd+tAEFpMjaPw4\/RHA=' \/>\n            <input type='hidden' class='gform_hidden' name='gform_unique_id' value='' \/>\n            <input type='hidden' class='gform_hidden' name='state_1' value='WyJbXSIsImE5MTExMmVjNTgxZGEyNjM5MzUyMjcxOTA5YmQyNjMwIl0=' \/>\n            <input type='hidden' autocomplete='off' class='gform_hidden' name='gform_target_page_number_1' id='gform_target_page_number_1' value='0' \/>\n            <input type='hidden' autocomplete='off' class='gform_hidden' name='gform_source_page_number_1' id='gform_source_page_number_1' value='1' \/>\n            <input type='hidden' name='gform_field_values' value='' \/>\n            \n        <\/div>\n                        <input type=\"hidden\" id=\"ct_checkjs_9be40cee5b0eee1462c82c6964087ff9\" name=\"ct_checkjs\" value=\"0\" \/><input\n                    class=\"apbct_special_field apbct_email_id__gravity_form\"\n                    name=\"apbct__email_id__gravity_form\"\n                    aria-label=\"apbct__label_id__gravity_form\"\n                    type=\"text\" size=\"30\" maxlength=\"200\" autocomplete=\"off\"\n                    value=\"\"\n                \/><\/form>\n                        <\/div><script>\ngform.initializeOnLoaded( function() {gformInitSpinner( 1, 'https:\/\/endlesssurf.com\/wp-content\/plugins\/gravityforms\/images\/spinner.svg', true );jQuery('#gform_ajax_frame_1').on('load',function(){var contents = jQuery(this).contents().find('*').html();var is_postback = contents.indexOf('GF_AJAX_POSTBACK') >= 0;if(!is_postback){return;}var form_content = jQuery(this).contents().find('#gform_wrapper_1');var is_confirmation = jQuery(this).contents().find('#gform_confirmation_wrapper_1').length > 0;var is_redirect = contents.indexOf('gformRedirect(){') >= 0;var is_form = form_content.length > 0 && ! is_redirect && ! is_confirmation;var mt = parseInt(jQuery('html').css('margin-top'), 10) + parseInt(jQuery('body').css('margin-top'), 10) + 100;if(is_form){jQuery('#gform_wrapper_1').html(form_content.html());if(form_content.hasClass('gform_validation_error')){jQuery('#gform_wrapper_1').addClass('gform_validation_error');} else {jQuery('#gform_wrapper_1').removeClass('gform_validation_error');}setTimeout( function() { \/* delay the scroll by 50 milliseconds to fix a bug in chrome *\/  }, 50 );if(window['gformInitDatepicker']) {gformInitDatepicker();}if(window['gformInitPriceFields']) {gformInitPriceFields();}var current_page = jQuery('#gform_source_page_number_1').val();gformInitSpinner( 1, 'https:\/\/endlesssurf.com\/wp-content\/plugins\/gravityforms\/images\/spinner.svg', true );jQuery(document).trigger('gform_page_loaded', [1, current_page]);window['gf_submitting_1'] = false;}else if(!is_redirect){var confirmation_content = jQuery(this).contents().find('.GF_AJAX_POSTBACK').html();if(!confirmation_content){confirmation_content = contents;}jQuery('#gform_wrapper_1').replaceWith(confirmation_content);jQuery(document).trigger('gform_confirmation_loaded', [1]);window['gf_submitting_1'] = false;wp.a11y.speak(jQuery('#gform_confirmation_message_1').text());}else{jQuery('#gform_1').append(contents);if(window['gformRedirect']) {gformRedirect();}}jQuery(document).trigger(\"gform_pre_post_render\", [{ formId: \"1\", currentPage: \"current_page\", abort: function() { this.preventDefault(); } }]);        if (event && event.defaultPrevented) {                return;        }        const gformWrapperDiv = document.getElementById( \"gform_wrapper_1\" );        if ( gformWrapperDiv ) {            const visibilitySpan = document.createElement( \"span\" );            visibilitySpan.id = \"gform_visibility_test_1\";            gformWrapperDiv.insertAdjacentElement( \"afterend\", visibilitySpan );        }        const visibilityTestDiv = document.getElementById( \"gform_visibility_test_1\" );        let postRenderFired = false;        function triggerPostRender() {            if ( postRenderFired ) {                return;            }            postRenderFired = true;            gform.core.triggerPostRenderEvents( 1, current_page );            if ( visibilityTestDiv ) {                visibilityTestDiv.parentNode.removeChild( visibilityTestDiv );            }        }        function debounce( func, wait, immediate ) {            var timeout;            return function() {                var context = this, args = arguments;                var later = function() {                    timeout = null;                    if ( !immediate ) func.apply( context, args );                };                var callNow = immediate && !timeout;                clearTimeout( timeout );                timeout = setTimeout( later, wait );                if ( callNow ) func.apply( context, args );            };        }        const debouncedTriggerPostRender = debounce( function() {            triggerPostRender();        }, 200 );        if ( visibilityTestDiv && visibilityTestDiv.offsetParent === null ) {            const observer = new MutationObserver( ( mutations ) => {                mutations.forEach( ( mutation ) => {                    if ( mutation.type === 'attributes' && visibilityTestDiv.offsetParent !== null ) {                        debouncedTriggerPostRender();                        observer.disconnect();                    }                });            });            observer.observe( document.body, {                attributes: true,                childList: false,                subtree: true,                attributeFilter: [ 'style', 'class' ],            });        } else {            triggerPostRender();        }    } );} );\n<\/script>\n\n","protected":false},"excerpt":{"rendered":"<p>Estamos em uma posi\u00e7\u00e3o privilegiada para conhecer os Surf Parks em desenvolvimento antes de seu an\u00fancio p\u00fablico, e podemos dizer com confian\u00e7a que vemos locais de surf do interior se expandindo para diferentes mercados globalmente. Por qu\u00ea? A procura pela experi\u00eancia de surf est\u00e1, sem d\u00favida, cada vez mais forte entre os consumidores que impulsionam&#8230;<\/p>\n","protected":false},"author":11,"featured_media":1867,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[326],"tags":[],"class_list":["post-1865","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-experience-design-br"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v24.4 (Yoast SEO v27.3) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>5 DICAS DE DESIGN DE SURF PARK PARA DESENVOLVEDORES | Endless Surf<\/title>\n<meta name=\"description\" content=\"Venue design is a very important step for surf park developments. Here&#039;s some key tips from our master-planning &amp; experience design experts.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/endlesssurf.com\/br\/2022\/08\/03\/5-dicas-de-design-de-surf-park-para-desenvolvedores\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"5 DICAS DE DESIGN DE SURF PARK PARA DESENVOLVEDORES\" \/>\n<meta property=\"og:description\" content=\"Estamos em uma posi\u00e7\u00e3o privilegiada para conhecer os Surf Parks em desenvolvimento antes de seu an\u00fancio p\u00fablico, e podemos dizer com confian\u00e7a que vemos\" \/>\n<meta property=\"og:url\" content=\"https:\/\/endlesssurf.com\/br\/2022\/08\/03\/5-dicas-de-design-de-surf-park-para-desenvolvedores\/\" \/>\n<meta property=\"og:site_name\" content=\"Endless Surf\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/facebook.com\/endlesssurfofficial\" \/>\n<meta property=\"article:published_time\" content=\"2022-08-03T05:15:29+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2022-11-10T07:28:44+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/endlesssurf.com\/wp-content\/uploads\/2022\/07\/Anthony-venue-design-article-image-1.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1440\" \/>\n\t<meta property=\"og:image:height\" content=\"900\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Tanner Wilson\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@endlesssurfpool\" \/>\n<meta name=\"twitter:site\" content=\"@endlesssurfpool\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Tanner Wilson\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"6 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/endlesssurf.com\\\/br\\\/2022\\\/08\\\/03\\\/5-dicas-de-design-de-surf-park-para-desenvolvedores\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/endlesssurf.com\\\/br\\\/2022\\\/08\\\/03\\\/5-dicas-de-design-de-surf-park-para-desenvolvedores\\\/\"},\"author\":{\"name\":\"Tanner Wilson\",\"@id\":\"https:\\\/\\\/endlesssurf.com\\\/br\\\/#\\\/schema\\\/person\\\/db915bb093dcab8131c3575ff1a55ba4\"},\"headline\":\"5 DICAS DE DESIGN DE SURF PARK PARA DESENVOLVEDORES\",\"datePublished\":\"2022-08-03T05:15:29+00:00\",\"dateModified\":\"2022-11-10T07:28:44+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/endlesssurf.com\\\/br\\\/2022\\\/08\\\/03\\\/5-dicas-de-design-de-surf-park-para-desenvolvedores\\\/\"},\"wordCount\":1301,\"publisher\":{\"@id\":\"https:\\\/\\\/endlesssurf.com\\\/br\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/endlesssurf.com\\\/br\\\/2022\\\/08\\\/03\\\/5-dicas-de-design-de-surf-park-para-desenvolvedores\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/endlesssurf.com\\\/wp-content\\\/uploads\\\/2022\\\/07\\\/Anthony-venue-design-article-image-1.png\",\"articleSection\":[\"Experience Design\"],\"inLanguage\":\"brazil\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/endlesssurf.com\\\/br\\\/2022\\\/08\\\/03\\\/5-dicas-de-design-de-surf-park-para-desenvolvedores\\\/\",\"url\":\"https:\\\/\\\/endlesssurf.com\\\/br\\\/2022\\\/08\\\/03\\\/5-dicas-de-design-de-surf-park-para-desenvolvedores\\\/\",\"name\":\"5 DICAS DE DESIGN DE SURF PARK PARA DESENVOLVEDORES | Endless Surf\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/endlesssurf.com\\\/br\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/endlesssurf.com\\\/br\\\/2022\\\/08\\\/03\\\/5-dicas-de-design-de-surf-park-para-desenvolvedores\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/endlesssurf.com\\\/br\\\/2022\\\/08\\\/03\\\/5-dicas-de-design-de-surf-park-para-desenvolvedores\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/endlesssurf.com\\\/wp-content\\\/uploads\\\/2022\\\/07\\\/Anthony-venue-design-article-image-1.png\",\"datePublished\":\"2022-08-03T05:15:29+00:00\",\"dateModified\":\"2022-11-10T07:28:44+00:00\",\"description\":\"Venue design is a very important step for surf park developments. Here's some key tips from our master-planning & experience design experts.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/endlesssurf.com\\\/br\\\/2022\\\/08\\\/03\\\/5-dicas-de-design-de-surf-park-para-desenvolvedores\\\/#breadcrumb\"},\"inLanguage\":\"brazil\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/endlesssurf.com\\\/br\\\/2022\\\/08\\\/03\\\/5-dicas-de-design-de-surf-park-para-desenvolvedores\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"brazil\",\"@id\":\"https:\\\/\\\/endlesssurf.com\\\/br\\\/2022\\\/08\\\/03\\\/5-dicas-de-design-de-surf-park-para-desenvolvedores\\\/#primaryimage\",\"url\":\"https:\\\/\\\/endlesssurf.com\\\/wp-content\\\/uploads\\\/2022\\\/07\\\/Anthony-venue-design-article-image-1.png\",\"contentUrl\":\"https:\\\/\\\/endlesssurf.com\\\/wp-content\\\/uploads\\\/2022\\\/07\\\/Anthony-venue-design-article-image-1.png\",\"width\":1440,\"height\":900},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/endlesssurf.com\\\/br\\\/2022\\\/08\\\/03\\\/5-dicas-de-design-de-surf-park-para-desenvolvedores\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/endlesssurf.com\\\/br\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"5 DICAS DE DESIGN DE SURF PARK PARA DESENVOLVEDORES\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/endlesssurf.com\\\/br\\\/#website\",\"url\":\"https:\\\/\\\/endlesssurf.com\\\/br\\\/\",\"name\":\"Endless Surf\",\"description\":\"Shaping the future of surf park technology\",\"publisher\":{\"@id\":\"https:\\\/\\\/endlesssurf.com\\\/br\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/endlesssurf.com\\\/br\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"brazil\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/endlesssurf.com\\\/br\\\/#organization\",\"name\":\"Endless Surf\",\"url\":\"https:\\\/\\\/endlesssurf.com\\\/br\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"brazil\",\"@id\":\"https:\\\/\\\/endlesssurf.com\\\/br\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/endlesssurf.com\\\/wp-content\\\/uploads\\\/2020\\\/05\\\/Screen-Shot-2020-05-18-at-4.38.08-PM.png\",\"contentUrl\":\"https:\\\/\\\/endlesssurf.com\\\/wp-content\\\/uploads\\\/2020\\\/05\\\/Screen-Shot-2020-05-18-at-4.38.08-PM.png\",\"width\":590,\"height\":452,\"caption\":\"Endless Surf\"},\"image\":{\"@id\":\"https:\\\/\\\/endlesssurf.com\\\/br\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/facebook.com\\\/endlesssurfofficial\",\"https:\\\/\\\/x.com\\\/endlesssurfpool\",\"https:\\\/\\\/instagram.com\\\/endlesssurfofficial\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/endlesssurf\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/endlesssurf.com\\\/br\\\/#\\\/schema\\\/person\\\/db915bb093dcab8131c3575ff1a55ba4\",\"name\":\"Tanner Wilson\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"brazil\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/03c11698bda06014e714f44709c0202fb235df0574386d9ff128e181ef2d39cf?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/03c11698bda06014e714f44709c0202fb235df0574386d9ff128e181ef2d39cf?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/03c11698bda06014e714f44709c0202fb235df0574386d9ff128e181ef2d39cf?s=96&d=mm&r=g\",\"caption\":\"Tanner Wilson\"},\"url\":\"https:\\\/\\\/endlesssurf.com\\\/br\\\/author\\\/tanner-wilsonwhitewaterwest-com\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"5 DICAS DE DESIGN DE SURF PARK PARA DESENVOLVEDORES | Endless Surf","description":"Venue design is a very important step for surf park developments. Here's some key tips from our master-planning & experience design experts.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/endlesssurf.com\/br\/2022\/08\/03\/5-dicas-de-design-de-surf-park-para-desenvolvedores\/","og_locale":"en_US","og_type":"article","og_title":"5 DICAS DE DESIGN DE SURF PARK PARA DESENVOLVEDORES","og_description":"Estamos em uma posi\u00e7\u00e3o privilegiada para conhecer os Surf Parks em desenvolvimento antes de seu an\u00fancio p\u00fablico, e podemos dizer com confian\u00e7a que vemos","og_url":"https:\/\/endlesssurf.com\/br\/2022\/08\/03\/5-dicas-de-design-de-surf-park-para-desenvolvedores\/","og_site_name":"Endless Surf","article_publisher":"https:\/\/facebook.com\/endlesssurfofficial","article_published_time":"2022-08-03T05:15:29+00:00","article_modified_time":"2022-11-10T07:28:44+00:00","og_image":[{"width":1440,"height":900,"url":"https:\/\/endlesssurf.com\/wp-content\/uploads\/2022\/07\/Anthony-venue-design-article-image-1.png","type":"image\/png"}],"author":"Tanner Wilson","twitter_card":"summary_large_image","twitter_creator":"@endlesssurfpool","twitter_site":"@endlesssurfpool","twitter_misc":{"Written by":"Tanner Wilson","Est. reading time":"6 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/endlesssurf.com\/br\/2022\/08\/03\/5-dicas-de-design-de-surf-park-para-desenvolvedores\/#article","isPartOf":{"@id":"https:\/\/endlesssurf.com\/br\/2022\/08\/03\/5-dicas-de-design-de-surf-park-para-desenvolvedores\/"},"author":{"name":"Tanner Wilson","@id":"https:\/\/endlesssurf.com\/br\/#\/schema\/person\/db915bb093dcab8131c3575ff1a55ba4"},"headline":"5 DICAS DE DESIGN DE SURF PARK PARA DESENVOLVEDORES","datePublished":"2022-08-03T05:15:29+00:00","dateModified":"2022-11-10T07:28:44+00:00","mainEntityOfPage":{"@id":"https:\/\/endlesssurf.com\/br\/2022\/08\/03\/5-dicas-de-design-de-surf-park-para-desenvolvedores\/"},"wordCount":1301,"publisher":{"@id":"https:\/\/endlesssurf.com\/br\/#organization"},"image":{"@id":"https:\/\/endlesssurf.com\/br\/2022\/08\/03\/5-dicas-de-design-de-surf-park-para-desenvolvedores\/#primaryimage"},"thumbnailUrl":"https:\/\/endlesssurf.com\/wp-content\/uploads\/2022\/07\/Anthony-venue-design-article-image-1.png","articleSection":["Experience Design"],"inLanguage":"brazil"},{"@type":"WebPage","@id":"https:\/\/endlesssurf.com\/br\/2022\/08\/03\/5-dicas-de-design-de-surf-park-para-desenvolvedores\/","url":"https:\/\/endlesssurf.com\/br\/2022\/08\/03\/5-dicas-de-design-de-surf-park-para-desenvolvedores\/","name":"5 DICAS DE DESIGN DE SURF PARK PARA DESENVOLVEDORES | Endless Surf","isPartOf":{"@id":"https:\/\/endlesssurf.com\/br\/#website"},"primaryImageOfPage":{"@id":"https:\/\/endlesssurf.com\/br\/2022\/08\/03\/5-dicas-de-design-de-surf-park-para-desenvolvedores\/#primaryimage"},"image":{"@id":"https:\/\/endlesssurf.com\/br\/2022\/08\/03\/5-dicas-de-design-de-surf-park-para-desenvolvedores\/#primaryimage"},"thumbnailUrl":"https:\/\/endlesssurf.com\/wp-content\/uploads\/2022\/07\/Anthony-venue-design-article-image-1.png","datePublished":"2022-08-03T05:15:29+00:00","dateModified":"2022-11-10T07:28:44+00:00","description":"Venue design is a very important step for surf park developments. Here's some key tips from our master-planning & experience design experts.","breadcrumb":{"@id":"https:\/\/endlesssurf.com\/br\/2022\/08\/03\/5-dicas-de-design-de-surf-park-para-desenvolvedores\/#breadcrumb"},"inLanguage":"brazil","potentialAction":[{"@type":"ReadAction","target":["https:\/\/endlesssurf.com\/br\/2022\/08\/03\/5-dicas-de-design-de-surf-park-para-desenvolvedores\/"]}]},{"@type":"ImageObject","inLanguage":"brazil","@id":"https:\/\/endlesssurf.com\/br\/2022\/08\/03\/5-dicas-de-design-de-surf-park-para-desenvolvedores\/#primaryimage","url":"https:\/\/endlesssurf.com\/wp-content\/uploads\/2022\/07\/Anthony-venue-design-article-image-1.png","contentUrl":"https:\/\/endlesssurf.com\/wp-content\/uploads\/2022\/07\/Anthony-venue-design-article-image-1.png","width":1440,"height":900},{"@type":"BreadcrumbList","@id":"https:\/\/endlesssurf.com\/br\/2022\/08\/03\/5-dicas-de-design-de-surf-park-para-desenvolvedores\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/endlesssurf.com\/br\/"},{"@type":"ListItem","position":2,"name":"5 DICAS DE DESIGN DE SURF PARK PARA DESENVOLVEDORES"}]},{"@type":"WebSite","@id":"https:\/\/endlesssurf.com\/br\/#website","url":"https:\/\/endlesssurf.com\/br\/","name":"Endless Surf","description":"Shaping the future of surf park technology","publisher":{"@id":"https:\/\/endlesssurf.com\/br\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/endlesssurf.com\/br\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"brazil"},{"@type":"Organization","@id":"https:\/\/endlesssurf.com\/br\/#organization","name":"Endless Surf","url":"https:\/\/endlesssurf.com\/br\/","logo":{"@type":"ImageObject","inLanguage":"brazil","@id":"https:\/\/endlesssurf.com\/br\/#\/schema\/logo\/image\/","url":"https:\/\/endlesssurf.com\/wp-content\/uploads\/2020\/05\/Screen-Shot-2020-05-18-at-4.38.08-PM.png","contentUrl":"https:\/\/endlesssurf.com\/wp-content\/uploads\/2020\/05\/Screen-Shot-2020-05-18-at-4.38.08-PM.png","width":590,"height":452,"caption":"Endless Surf"},"image":{"@id":"https:\/\/endlesssurf.com\/br\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/facebook.com\/endlesssurfofficial","https:\/\/x.com\/endlesssurfpool","https:\/\/instagram.com\/endlesssurfofficial","https:\/\/www.linkedin.com\/company\/endlesssurf"]},{"@type":"Person","@id":"https:\/\/endlesssurf.com\/br\/#\/schema\/person\/db915bb093dcab8131c3575ff1a55ba4","name":"Tanner Wilson","image":{"@type":"ImageObject","inLanguage":"brazil","@id":"https:\/\/secure.gravatar.com\/avatar\/03c11698bda06014e714f44709c0202fb235df0574386d9ff128e181ef2d39cf?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/03c11698bda06014e714f44709c0202fb235df0574386d9ff128e181ef2d39cf?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/03c11698bda06014e714f44709c0202fb235df0574386d9ff128e181ef2d39cf?s=96&d=mm&r=g","caption":"Tanner Wilson"},"url":"https:\/\/endlesssurf.com\/br\/author\/tanner-wilsonwhitewaterwest-com\/"}]}},"_links":{"self":[{"href":"https:\/\/endlesssurf.com\/br\/wp-json\/wp\/v2\/posts\/1865","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/endlesssurf.com\/br\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/endlesssurf.com\/br\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/endlesssurf.com\/br\/wp-json\/wp\/v2\/users\/11"}],"replies":[{"embeddable":true,"href":"https:\/\/endlesssurf.com\/br\/wp-json\/wp\/v2\/comments?post=1865"}],"version-history":[{"count":0,"href":"https:\/\/endlesssurf.com\/br\/wp-json\/wp\/v2\/posts\/1865\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/endlesssurf.com\/br\/wp-json\/wp\/v2\/media\/1867"}],"wp:attachment":[{"href":"https:\/\/endlesssurf.com\/br\/wp-json\/wp\/v2\/media?parent=1865"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/endlesssurf.com\/br\/wp-json\/wp\/v2\/categories?post=1865"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/endlesssurf.com\/br\/wp-json\/wp\/v2\/tags?post=1865"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}